{"id":33950,"date":"2026-02-10T08:34:43","date_gmt":"2026-02-10T07:34:43","guid":{"rendered":"https:\/\/frotepartner.ch\/?post_type=employment&#038;p=33950"},"modified":"2026-02-10T08:34:45","modified_gmt":"2026-02-10T07:34:45","slug":"assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100","status":"publish","type":"employment","link":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/","title":{"rendered":"Assistentin\/Sachbeabeiterin Advokatur und Notariat (w\/m) 50-100%"},"content":{"rendered":"\n<p><strong>PROFIL<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kaufm\u00e4nnischen Ausbildung oder einer Matura bzw. einer h\u00f6heren Fachausbildung.<\/li>\n\n\n\n<li>Sehr gute Kenntnisse der deutschen Sprache in Wort und Schrift sowie idealerweise gute Kenntnisse in Franz\u00f6sisch<\/li>\n\n\n\n<li>Erstellen von Rechtsschriften, notariellen Urkunden und weiteren juristischen Dokumenten<\/li>\n\n\n\n<li>Verwaltung von Klientendossier<\/li>\n\n\n\n<li>F\u00fchrung notarieller Register und Klientengelderkonten<\/li>\n\n\n\n<li>Rechnungsstellung<\/li>\n\n\n\n<li>T\u00e4glichem Kontakt mit der Klientschaft und den Beh\u00f6rden (Gericht, Staatsanwaltschaft, Register\u00e4mter, etc.).<\/li>\n\n\n\n<li>Verfassung und Bearbeitung allgemeine Korrespondenz in vorwiegend deutscher Sprache.<\/li>\n<\/ul>\n\n\n\n<p><strong>WIR BIETEN IHNEN<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kollegiales Arbeitsumfeld<\/li>\n\n\n\n<li>Moderne B\u00fcror\u00e4umlichkeiten an zentraler Lage in der Stadt Biel<\/li>\n\n\n\n<li>Abwechslungsreiche und verantwortungsvolle T\u00e4tigkeit<\/li>\n\n\n\n<li>Zeitgem\u00e4sse Arbeitsbedingungen<\/li>\n<\/ul>\n\n\n\n<p>Stellenantritt ab sofort oder nach Vereinbarung<\/p>\n\n\n\n<p><strong>Sind Sie an dieser Stelle interessiert? Dann senden Sie uns Ihre Bewerbung per E-Mail oder per Post an : Fr\u00f4t\u00e9 &amp; Partner AG, Rechtsanwalt und Notar Daniel Gehrig, Zentralplatz 51, 2501 Biel oder dg@frotepartner.ch.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PROFIL WIR BIETEN IHNEN Stellenantritt ab sofort oder nach Vereinbarung Sind Sie an dieser Stelle interessiert? Dann senden Sie uns Ihre Bewerbung per E-Mail oder per Post an : Fr\u00f4t\u00e9 &amp; Partner AG, Rechtsanwalt und Notar Daniel Gehrig, Zentralplatz 51, 2501 Biel oder dg@frotepartner.ch.<\/p>\n","protected":false},"featured_media":31439,"template":"","class_list":["post-33950","employment","type-employment","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assistentin\/Sachbeabeiterin Advokatur und Notariat (w\/m) 50-100% - Fr\u00f4t\u00e9 &amp; Partner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistentin\/Sachbeabeiterin Advokatur und Notariat (w\/m) 50-100% - Fr\u00f4t\u00e9 &amp; Partner\" \/>\n<meta property=\"og:description\" content=\"PROFIL WIR BIETEN IHNEN Stellenantritt ab sofort oder nach Vereinbarung Sind Sie an dieser Stelle interessiert? Dann senden Sie uns Ihre Bewerbung per E-Mail oder per Post an : Fr\u00f4t\u00e9 &amp; Partner AG, Rechtsanwalt und Notar Daniel Gehrig, Zentralplatz 51, 2501 Biel oder dg@frotepartner.ch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/\" \/>\n<meta property=\"og:site_name\" content=\"Fr\u00f4t\u00e9 &amp; Partner\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T07:34:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frotepartner.ch\/wp-content\/uploads\/2024\/02\/DMA7358-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/\",\"url\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/\",\"name\":\"Assistentin\\\/Sachbeabeiterin Advokatur und Notariat (w\\\/m) 50-100% - Fr\u00f4t\u00e9 &amp; Partner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frotepartner.ch\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/DMA7358-scaled.jpg\",\"datePublished\":\"2026-02-10T07:34:43+00:00\",\"dateModified\":\"2026-02-10T07:34:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frotepartner.ch\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/DMA7358-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/frotepartner.ch\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/DMA7358-scaled.jpg\",\"width\":2560,\"height\":1705,\"caption\":\"Fr\u00f4t\u00e9 &amp; Partner Neuch\u00e2tel, 15.12.2023 Photo David Marchon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emploi\",\"item\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/emploi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assistentin\\\/Sachbeabeiterin Advokatur und Notariat (w\\\/m) 50-100%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/\",\"name\":\"Fr\u00f4t\u00e9 &amp; Partner\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/#organization\",\"name\":\"Fr\u00f4t\u00e9 &amp; Partner\",\"url\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/frotepartner.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/FPartner_fren_-_Leonie_Schoeb.jpg\",\"contentUrl\":\"https:\\\/\\\/frotepartner.ch\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/FPartner_fren_-_Leonie_Schoeb.jpg\",\"width\":1773,\"height\":523,\"caption\":\"Fr\u00f4t\u00e9 &amp; Partner\"},\"image\":{\"@id\":\"https:\\\/\\\/frotepartner.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/68832912\\\/admin\\\/feed\\\/posts\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assistentin\/Sachbeabeiterin Advokatur und Notariat (w\/m) 50-100% - Fr\u00f4t\u00e9 &amp; Partner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/","og_locale":"de_DE","og_type":"article","og_title":"Assistentin\/Sachbeabeiterin Advokatur und Notariat (w\/m) 50-100% - Fr\u00f4t\u00e9 &amp; Partner","og_description":"PROFIL WIR BIETEN IHNEN Stellenantritt ab sofort oder nach Vereinbarung Sind Sie an dieser Stelle interessiert? Dann senden Sie uns Ihre Bewerbung per E-Mail oder per Post an : Fr\u00f4t\u00e9 &amp; Partner AG, Rechtsanwalt und Notar Daniel Gehrig, Zentralplatz 51, 2501 Biel oder dg@frotepartner.ch.","og_url":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/","og_site_name":"Fr\u00f4t\u00e9 &amp; Partner","article_modified_time":"2026-02-10T07:34:45+00:00","og_image":[{"width":2560,"height":1705,"url":"https:\/\/frotepartner.ch\/wp-content\/uploads\/2024\/02\/DMA7358-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/","url":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/","name":"Assistentin\/Sachbeabeiterin Advokatur und Notariat (w\/m) 50-100% - Fr\u00f4t\u00e9 &amp; Partner","isPartOf":{"@id":"https:\/\/frotepartner.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/#primaryimage"},"image":{"@id":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/#primaryimage"},"thumbnailUrl":"https:\/\/frotepartner.ch\/wp-content\/uploads\/2024\/02\/DMA7358-scaled.jpg","datePublished":"2026-02-10T07:34:43+00:00","dateModified":"2026-02-10T07:34:45+00:00","breadcrumb":{"@id":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/#primaryimage","url":"https:\/\/frotepartner.ch\/wp-content\/uploads\/2024\/02\/DMA7358-scaled.jpg","contentUrl":"https:\/\/frotepartner.ch\/wp-content\/uploads\/2024\/02\/DMA7358-scaled.jpg","width":2560,"height":1705,"caption":"Fr\u00f4t\u00e9 &amp; Partner Neuch\u00e2tel, 15.12.2023 Photo David Marchon"},{"@type":"BreadcrumbList","@id":"https:\/\/frotepartner.ch\/de\/emploi\/assistentin-sachbeabeiterin-advokatur-und-notariat-w-m-50-100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frotepartner.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Emploi","item":"https:\/\/frotepartner.ch\/de\/emploi\/"},{"@type":"ListItem","position":3,"name":"Assistentin\/Sachbeabeiterin Advokatur und Notariat (w\/m) 50-100%"}]},{"@type":"WebSite","@id":"https:\/\/frotepartner.ch\/de\/#website","url":"https:\/\/frotepartner.ch\/de\/","name":"Fr\u00f4t\u00e9 &amp; Partner","description":"","publisher":{"@id":"https:\/\/frotepartner.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frotepartner.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/frotepartner.ch\/de\/#organization","name":"Fr\u00f4t\u00e9 &amp; Partner","url":"https:\/\/frotepartner.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/frotepartner.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/frotepartner.ch\/wp-content\/uploads\/2023\/10\/FPartner_fren_-_Leonie_Schoeb.jpg","contentUrl":"https:\/\/frotepartner.ch\/wp-content\/uploads\/2023\/10\/FPartner_fren_-_Leonie_Schoeb.jpg","width":1773,"height":523,"caption":"Fr\u00f4t\u00e9 &amp; Partner"},"image":{"@id":"https:\/\/frotepartner.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/68832912\/admin\/feed\/posts\/"]}]}},"_links":{"self":[{"href":"https:\/\/frotepartner.ch\/de\/wp-json\/wp\/v2\/employment\/33950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frotepartner.ch\/de\/wp-json\/wp\/v2\/employment"}],"about":[{"href":"https:\/\/frotepartner.ch\/de\/wp-json\/wp\/v2\/types\/employment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frotepartner.ch\/de\/wp-json\/wp\/v2\/media\/31439"}],"wp:attachment":[{"href":"https:\/\/frotepartner.ch\/de\/wp-json\/wp\/v2\/media?parent=33950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}